{"id":713,"date":"2025-12-22T09:43:41","date_gmt":"2025-12-22T09:43:41","guid":{"rendered":"https:\/\/valentini.creazionesitoefficace.it\/maschinenpark\/"},"modified":"2026-04-01T09:30:20","modified_gmt":"2026-04-01T09:30:20","slug":"maschinenpark","status":"publish","type":"page","link":"https:\/\/www.valentiniutensili.com\/de\/maschinenpark\/","title":{"rendered":"Maschinenpark"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"713\" class=\"elementor elementor-713 elementor-52\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b2509e e-flex e-con-boxed e-con e-parent\" data-id=\"4b2509e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8518b8e elementor-widget elementor-widget-text-editor\" data-id=\"8518b8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">Produktionsbereiche und <\/span>Maschinenpark<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-283d5dc elementor-widget elementor-widget-heading\" data-id=\"283d5dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Zwei Produktionsst\u00e4tten, ein vollst\u00e4ndiger und organisierter Maschinenpark zur Gew\u00e4hrleistung von Effizienz und Kontrolle.<\/span>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3422df2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3422df2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33fd33a e-con-full e-flex e-con e-child\" data-id=\"33fd33a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82f3f4b elementor-widget elementor-widget-image\" data-id=\"82f3f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"PRODUKTIONSST\u00c4TTE-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzE0LCJ1cmwiOiJodHRwczpcL1wvd3d3LnZhbGVudGluaXV0ZW5zaWxpLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1NUQUJJTElNRU5UTy0xLmpwZyJ9\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-1-1024x576.jpg\" class=\"attachment-large size-large wp-image-714\" alt=\"\" srcset=\"https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-1-1024x576.jpg 1024w, https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-1-300x169.jpg 300w, https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-1-768x432.jpg 768w, https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-1.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2de32e elementor-widget elementor-widget-image\" data-id=\"b2de32e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"PRODUKTIONSST\u00c4TTE-2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzE1LCJ1cmwiOiJodHRwczpcL1wvd3d3LnZhbGVudGluaXV0ZW5zaWxpLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNlwvMDFcL1NUQUJJTElNRU5UTy0yLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-2-1024x576.jpg\" class=\"attachment-large size-large wp-image-715\" alt=\"\" srcset=\"https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-2-1024x576.jpg 1024w, https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-2-300x169.jpg 300w, https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-2-768x432.jpg 768w, https:\/\/www.valentiniutensili.com\/wp-content\/uploads\/2026\/01\/STABILIMENTO-2.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e90b7b e-flex e-con-boxed e-con e-parent\" data-id=\"7e90b7b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-898a4fa elementor-widget elementor-widget-shortcode\" data-id=\"898a4fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<table id=\"tablepress-1\" class=\"tablepress tablepress-id-1 tbody-has-connected-cells\">\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-1\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>TORNITURA A CONTROLLO NUMERICO<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>INGOMBRO MAX.<\/strong><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">MAZAK INTEGREX 200 MARK IV<\/td><td class=\"column-2\">12<\/td><td class=\"column-3\">MATRIX<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1500mm x \u00d8 420mm<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">MAZAK INTEGREX I-200S - SMOOTH X<\/td><td class=\"column-2\">56<\/td><td class=\"column-3\">SMOOTH<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 658mm<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">MAZAK INTEGREX I-200 - SMOOTH X<\/td><td class=\"column-2\">64<\/td><td class=\"column-3\">SMOOTH<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 658mm<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">MAZAK INTEGREX 200Y<\/td><td class=\"column-2\">16<\/td><td class=\"column-3\">MAZATROL 640T<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 420mm<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">MAZAK INTEGREX I300<\/td><td class=\"column-2\">50<\/td><td class=\"column-3\">MATRIX 2<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1500mm x \u00d8 650mm<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">MAZAK SUPER QUICK TURN 250<\/td><td class=\"column-2\">17<\/td><td class=\"column-3\">MAZATROL 640T<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 500mm x \u00d8 380 mm<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">MAZAK QUICKTURN SMART 350M<\/td><td class=\"column-2\">51<\/td><td class=\"column-3\">SMART<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 720 mm x \u00d8 420 mm<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">MORI SEIKI NL2000Y\/500<\/td><td class=\"column-2\">7<\/td><td class=\"column-3\">MSX 850<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 500mm x \u00d8380 mm<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">SIRMA M32-V<\/td><td class=\"column-2\">9<\/td><td class=\"column-3\">CITIZEN<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 320mm x \u00d8 32mm<\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">VEMAS SHUABLIN 125<\/td><td class=\"column-2\">23<\/td><td class=\"column-3\">FANUC 18i<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 400mm x \u00d8 200mm<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">NAKAMURA SC-300IIMY<\/td><td class=\"column-2\">86<\/td><td class=\"column-3\">FANUC 0iTF<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 713mm x \u00d8 360mm<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>FRESATURA A CONTROLLO NUMERICO<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">MAZAK VARIAXIS 630-5X-II<\/td><td class=\"column-2\">13 -49<\/td><td class=\"column-3\">MATRIX (20 pallet)<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">\u00d8 730mm x h 500mm<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">MAZAK VARIAXIS 6302 T<\/td><td class=\"column-2\">15<\/td><td class=\"column-3\">MATRIX<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">765mm x 630mm x h 740mm<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">MAZAK VARIAXIS 6302 T<\/td><td class=\"column-2\">39<\/td><td class=\"column-3\">MATRIX<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">765mm x 630mm x h 740mm<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">MAZAK VARIAXIS I700T SMOOTH<\/td><td class=\"column-2\">59<\/td><td class=\"column-3\">SMOOTH<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">1100mm x 630mm x h 700mm<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">YASDA PX30i<\/td><td class=\"column-2\">98<\/td><td class=\"column-3\">FANUC 31i-B5<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">680mm x 400mm x 500mm<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">DECKEL MAHO DMU 70 V<\/td><td class=\"column-2\">24<\/td><td class=\"column-3\">HEIDENHAIN TNC 46<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">710mm x 520mm X h 520mm<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">MIKRON MILL P 500 U<\/td><td class=\"column-2\">87<\/td><td class=\"column-3\">HEIDENHAIN TNC640 ( 5 pallet)<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">500mm x 600mm x h 450mm<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">OKUMA MA500H II<\/td><td class=\"column-2\">88<\/td><td class=\"column-3\">OSP P300MA ( 6 pallet)<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">700mm x 900mm x h 780mm<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>FRESATURA\/TORNITURA MANUALE<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">FEHLMAN PICOMAX 54<\/td><td class=\"column-2\">22<\/td><td class=\"column-3\">HEIDENHAIN TNC 320<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">500mm x 250mm x 160mm<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">RAMBAUDI M2<\/td><td class=\"column-2\">37<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">1000mm x 300mm x 200mm<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">RIGIVA V.2<\/td><td class=\"column-2\">38<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">900mm x 210mm x 400mm<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">ALCOR<\/td><td class=\"column-2\">42<\/td><td class=\"column-3\">HEIDENHAIN TNC 530<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">750mm x 450mm x 525mm<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">PARPAS<\/td><td class=\"column-2\">43<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">900mm x 300mm X 350mm<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">ALCOR 220<\/td><td class=\"column-2\">62<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">750mm x 430mm x 300mm<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">TORNIO HARRISON M450<\/td><td class=\"column-2\">41<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 430mm<\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">INVEMA FR 40X1000<\/td><td class=\"column-2\">57<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">1000mm x 630mm x 280 mm<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>AFFILATURA A CONTROLLO NUMERICO<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">WALTER HELITRONIC POWER <\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">ANDRON HMC 400<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 185mm x \u00d8 100mm<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">WALTER POWER PRODUCTION <\/td><td class=\"column-2\">2<\/td><td class=\"column-3\">ANDRON HMC 500<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 185mm x \u00d8 100mm<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">WALTER DIAMOND <\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">ANDRON HMC 500<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 185mm x \u00d8 100mm<\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">WALTER VISION <\/td><td class=\"column-2\">4<\/td><td class=\"column-3\">ANDRON HMC 600<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 370mm x \u00d8 320mm<\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">WALTER HELITRONIC VISION <\/td><td class=\"column-2\">33 - 47<\/td><td class=\"column-3\">FANUC 31i<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 370mm x \u00d8 320mm<\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">WALTER HELITRONIC VISION 400L<\/td><td class=\"column-2\">66<\/td><td class=\"column-3\">FANUC<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 420mm x \u00d8 360mm<\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>AFFILATURA MANUALE<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">NESI C500<\/td><td class=\"column-2\">79-A \/<br \/>\n 79-B<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 680 mm x \u00d8 275 mm<\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">NESI C400<\/td><td class=\"column-2\">79 C-D-E-F<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 560mm x \u00d8 250 mm<\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>RETTIFICA CNC IN TONDO E TANGEZIALE<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">STUDER S31 <\/td><td class=\"column-2\">5<\/td><td class=\"column-3\">FANUC 16i<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 350mm<\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">KELLENBERGER UR175\/1000 KELCO 120<\/td><td class=\"column-2\">19<\/td><td class=\"column-3\">HEIDENHAIN<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 350mm<\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">KELLENBERGER VIARIA 100\/175<\/td><td class=\"column-2\">20<\/td><td class=\"column-3\">HEIDENHAIN<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 350mm<\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">STUDER S30-1<\/td><td class=\"column-2\">58<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8 350mm<\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">STUDER S41<\/td><td class=\"column-2\">69<\/td><td class=\"column-3\">FANUC 31i<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1600mm x \u00d8 450mm<\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">STUDER S41<\/td><td class=\"column-2\">65<\/td><td class=\"column-3\">FANUC 31i<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1600mm x \u00d8 550mm<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">ROSA IRON 11.6<\/td><td class=\"column-2\">27<\/td><td class=\"column-3\">SIEMENS<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x 650mm x h 560mm<\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">ROSA IRON 11.6<\/td><td class=\"column-2\">35<\/td><td class=\"column-3\">SIEMENS<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x 550mm x h 560mm<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">ROSA STEEL 11.7<\/td><td class=\"column-2\">60<\/td><td class=\"column-3\">SIEMENS<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x 500mm x h 560mm<\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">KELLENBERGER 1000 UR-RS<\/td><td class=\"column-2\">89<\/td><td class=\"column-3\">FANUC 31i<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">L 1000mm x \u00d8400mm<\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>ELETTROEROSIONE A CONTROLLO NUMERICO<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">SODICK AQ327L<\/td><td class=\"column-2\">25<\/td><td class=\"column-3\">LQ33W<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">370mm x 270mm x 220mm<\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\">SODICK AG60L<\/td><td class=\"column-2\">70<\/td><td class=\"column-3\">ELETTROEROSIONE A TUFFO<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">750mm x 550mm x 400mm<\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td class=\"column-1\">SODICK ALC600G<\/td><td class=\"column-2\">91<\/td><td class=\"column-3\">CNC SODICK SPW<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">600mm x 400mm x 350mm<\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>SALDATURA AUTOMATICA<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">GENERATORE POWER CUBE 12,5KW SERIE SA\/400 2H<\/td><td class=\"column-2\">97<\/td><td class=\"column-3\">GENERATORE A INDUZIONE<\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td colspan=\"5\" class=\"column-1\"><span style=\"color:#129245;\"><strong>MISURAZIONE E CONTROLLO<\/strong><\/span><\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\"><strong>MODELLO<\/strong><\/td><td class=\"column-2\"><strong><\/strong><\/td><td class=\"column-3\"><strong>TIPO DI CONTROLLO<\/strong><\/td><td class=\"column-4\"><strong><\/strong><\/td><td class=\"column-5\"><strong>CAMPO MAX. DI LAVORO<\/strong><\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">ZEISS PRISMO 5<\/td><td class=\"column-2\">10<\/td><td class=\"column-3\">CENTRO DI MISURA<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">700mm x 900mm x 500mm<\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td class=\"column-1\">ZEISS ACCURA<\/td><td class=\"column-2\">53<\/td><td class=\"column-3\">CENTRO DI MISURA<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">900mm x 1200mm x 800mm<\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\">TAYLOR HOBSON TALYROND 265 MRA<\/td><td class=\"column-2\">11-A<\/td><td class=\"column-3\">ROTONDIMETRO<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">\u00d8 300mm<\/td>\n<\/tr>\n<tr class=\"row-71\">\n\t<td class=\"column-1\">TAYLOR HOBSON FORM TALYSURF S6 PGI<\/td><td class=\"column-2\">11-B<\/td><td class=\"column-3\">PROFILOMETRO DI SUPERFICIE<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">120mm x 450mm x 6mm<\/td>\n<\/tr>\n<tr class=\"row-72\">\n\t<td class=\"column-1\">TAYLOR HOBSON FORM TALYSURF PGI800<\/td><td class=\"column-2\">48<\/td><td class=\"column-3\">PROFILOMETRO DI SUPERFICIE<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">400mm x 800mm x 1200mm<\/td>\n<\/tr>\n<tr class=\"row-73\">\n\t<td class=\"column-1\">WALTER HELICHECK PRO<\/td><td class=\"column-2\">66\/1<\/td><td class=\"column-3\">CMM OTTICA<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">270mm x 250mm x 355mm<\/td>\n<\/tr>\n<tr class=\"row-74\">\n\t<td class=\"column-1\">ZEISS O-DETECT<\/td><td class=\"column-2\">94<\/td><td class=\"column-3\">CMM OTTICA<\/td><td class=\"column-4\"><\/td><td class=\"column-5\">300mm x 200mm x 200mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-1 from cache --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Produktionsbereiche und Maschinenpark Zwei Produktionsst\u00e4tten, ein vollst\u00e4ndiger und organisierter Maschinenpark zur Gew\u00e4hrleistung von Effizienz und Kontrolle.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-713","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/pages\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/comments?post=713"}],"version-history":[{"count":1,"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/pages\/713\/revisions"}],"predecessor-version":[{"id":717,"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/pages\/713\/revisions\/717"}],"wp:attachment":[{"href":"https:\/\/www.valentiniutensili.com\/de\/wp-json\/wp\/v2\/media?parent=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}